{"id":21,"count":7,"description":"","link":"https:\/\/www.laboratorioripoll.com\/en\/product-category\/veterinaria\/antibioticos\/","name":"Antibi\u00f3ticos","slug":"antibioticos","taxonomy":"product_cat","parent":20,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antibi\u00f3ticos archivos - Laboratorio Ripoll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laboratorioripoll.com\/en\/product-category\/veterinaria\/antibioticos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antibi\u00f3ticos archivos - Laboratorio Ripoll\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laboratorioripoll.com\/en\/product-category\/veterinaria\/antibioticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Laboratorio Ripoll\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/\",\"url\":\"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/\",\"name\":\"Antibi\u00f3ticos archivos - Laboratorio Ripoll\",\"isPartOf\":{\"@id\":\"https:\/\/www.laboratorioripoll.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.laboratorioripoll.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veterinaria\",\"item\":\"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antibi\u00f3ticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.laboratorioripoll.com\/#website\",\"url\":\"https:\/\/www.laboratorioripoll.com\/\",\"name\":\"Laboratorio Ripoll\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.laboratorioripoll.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.laboratorioripoll.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.laboratorioripoll.com\/#organization\",\"name\":\"Laboratorio Ripoll\",\"url\":\"https:\/\/www.laboratorioripoll.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.laboratorioripoll.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.laboratorioripoll.com\/wp-content\/uploads\/2021\/08\/Ripoll-Logo.svg\",\"contentUrl\":\"https:\/\/www.laboratorioripoll.com\/wp-content\/uploads\/2021\/08\/Ripoll-Logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Laboratorio Ripoll\"},\"image\":{\"@id\":\"https:\/\/www.laboratorioripoll.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antibi\u00f3ticos archivos - Laboratorio Ripoll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laboratorioripoll.com\/en\/product-category\/veterinaria\/antibioticos\/","og_locale":"en_US","og_type":"article","og_title":"Antibi\u00f3ticos archivos - Laboratorio Ripoll","og_url":"https:\/\/www.laboratorioripoll.com\/en\/product-category\/veterinaria\/antibioticos\/","og_site_name":"Laboratorio Ripoll","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/","url":"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/","name":"Antibi\u00f3ticos archivos - Laboratorio Ripoll","isPartOf":{"@id":"https:\/\/www.laboratorioripoll.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/antibioticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.laboratorioripoll.com\/"},{"@type":"ListItem","position":2,"name":"Veterinaria","item":"https:\/\/www.laboratorioripoll.com\/product-category\/veterinaria\/"},{"@type":"ListItem","position":3,"name":"Antibi\u00f3ticos"}]},{"@type":"WebSite","@id":"https:\/\/www.laboratorioripoll.com\/#website","url":"https:\/\/www.laboratorioripoll.com\/","name":"Laboratorio Ripoll","description":"","publisher":{"@id":"https:\/\/www.laboratorioripoll.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laboratorioripoll.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.laboratorioripoll.com\/#organization","name":"Laboratorio Ripoll","url":"https:\/\/www.laboratorioripoll.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.laboratorioripoll.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.laboratorioripoll.com\/wp-content\/uploads\/2021\/08\/Ripoll-Logo.svg","contentUrl":"https:\/\/www.laboratorioripoll.com\/wp-content\/uploads\/2021\/08\/Ripoll-Logo.svg","width":1,"height":1,"caption":"Laboratorio Ripoll"},"image":{"@id":"https:\/\/www.laboratorioripoll.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.laboratorioripoll.com\/en\/wp-json\/wp\/v2\/product_cat\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laboratorioripoll.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.laboratorioripoll.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.laboratorioripoll.com\/en\/wp-json\/wp\/v2\/product_cat\/20"}],"wp:post_type":[{"href":"https:\/\/www.laboratorioripoll.com\/en\/wp-json\/wp\/v2\/product?product_cat=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}